{"id":948,"count":1,"description":"","link":"https:\/\/basi.de\/en\/tag\/fire\/","name":"Fire","slug":"fire","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fire Archive - Basi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/basi.de\/en\/tag\/fire\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fire Archive - Basi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/basi.de\/en\/tag\/fire\/\" \/>\n<meta property=\"og:site_name\" content=\"Basi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/basi.de\\\/en\\\/tag\\\/fire\\\/\",\"url\":\"https:\\\/\\\/basi.de\\\/en\\\/tag\\\/fire\\\/\",\"name\":\"Fire Archive - Basi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/basi.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/basi.de\\\/en\\\/tag\\\/fire\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/basi.de\\\/en\\\/tag\\\/fire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/basi.de\\\/en\\\/basi-federal-working-group-for-safety-and-health-at-work\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/basi.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/basi.de\\\/en\\\/\",\"name\":\"Bundesarbeitsgemeinschaft f\u00fcr Sicherheit und Gesundheit bei der Arbeit\",\"description\":\"Federal Working Group for Safety and Health at Work - Basi\",\"publisher\":{\"@id\":\"https:\\\/\\\/basi.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/basi.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/basi.de\\\/en\\\/#organization\",\"name\":\"Bundesarbeitsgemeinschaft f\u00fcr Sicherheit und Gesundheit bei der Arbeit\",\"url\":\"https:\\\/\\\/basi.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/basi.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/basi.de\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Basi_Logo_mit_text_deutsch.png\",\"contentUrl\":\"https:\\\/\\\/basi.de\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Basi_Logo_mit_text_deutsch.png\",\"width\":899,\"height\":310,\"caption\":\"Bundesarbeitsgemeinschaft f\u00fcr Sicherheit und Gesundheit bei der Arbeit\"},\"image\":{\"@id\":\"https:\\\/\\\/basi.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fire Archive - Basi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/basi.de\/en\/tag\/fire\/","og_locale":"en_US","og_type":"article","og_title":"Fire Archive - Basi","og_url":"https:\/\/basi.de\/en\/tag\/fire\/","og_site_name":"Basi","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/basi.de\/en\/tag\/fire\/","url":"https:\/\/basi.de\/en\/tag\/fire\/","name":"Fire Archive - Basi","isPartOf":{"@id":"https:\/\/basi.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/basi.de\/en\/tag\/fire\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/basi.de\/en\/tag\/fire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/basi.de\/en\/basi-federal-working-group-for-safety-and-health-at-work\/"},{"@type":"ListItem","position":2,"name":"Fire"}]},{"@type":"WebSite","@id":"https:\/\/basi.de\/en\/#website","url":"https:\/\/basi.de\/en\/","name":"Bundesarbeitsgemeinschaft f\u00fcr Sicherheit und Gesundheit bei der Arbeit","description":"Federal Working Group for Safety and Health at Work - Basi","publisher":{"@id":"https:\/\/basi.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/basi.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/basi.de\/en\/#organization","name":"Bundesarbeitsgemeinschaft f\u00fcr Sicherheit und Gesundheit bei der Arbeit","url":"https:\/\/basi.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/basi.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/basi.de\/wp-content\/uploads\/2024\/07\/Basi_Logo_mit_text_deutsch.png","contentUrl":"https:\/\/basi.de\/wp-content\/uploads\/2024\/07\/Basi_Logo_mit_text_deutsch.png","width":899,"height":310,"caption":"Bundesarbeitsgemeinschaft f\u00fcr Sicherheit und Gesundheit bei der Arbeit"},"image":{"@id":"https:\/\/basi.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/basi.de\/en\/wp-json\/wp\/v2\/tags\/948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basi.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/basi.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/basi.de\/en\/wp-json\/wp\/v2\/posts?tags=948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}